{"id":5707,"date":"2026-03-24T17:08:01","date_gmt":"2026-03-24T15:08:01","guid":{"rendered":"https:\/\/www.hannover-tourismus.de\/tickets-touren\/hannovernascht-list-oststadt\/"},"modified":"2026-06-11T12:05:08","modified_gmt":"2026-06-11T10:05:08","slug":"hannovernascht-list-oststadt","status":"publish","type":"tickets-touren","link":"https:\/\/www.hannover-tourismus.de\/da\/tickets-touren\/hannovernascht-list-oststadt\/","title":{"rendered":"Hanno(ver)nascht! Liste\/\u00d8stby"},"template":"","meta":{"tt_tourart_option":"beides","tt_termin_fenster":"Januar - November","tt_termine":{"item-0":{"tt_termine_details":"jeden 1. und 4. Samstag um 11:00 Uhr"}},"tt_art_der_tour":["rundgaenge"],"tt_thema":["stadtteile","kulinarik"],"tt_stadtteile":["list"],"tt_dauer":"3","tt_date_selector":"true","tt_date_rec":{"rrule":"DTSTART=20260103T000000Z;FREQ=WEEKLY;INTERVAL=4;BYDAY=SA;COUNT=5","dates":[]},"tt_date_man":{"rrule":"","dates":[]},"tt_teaserbild":"5708","tt_teasertext":"Genie\u00dfen Sie bei einem gem\u00fctlichen Stadtbummel durch den Stadtteil Hannover List die kulinarische Vielfalt Hannovers und entdecken Sie traditionelle Lokale, charmante Caf\u00e9s und urige Kneipen.","tt_hero_image":"5709","tt_beschreibung":"<div class=\"elementor-element elementor-element-db63c7a elementor-widget elementor-widget-text-editor\" data-id=\"db63c7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p data-start=\"245\" data-end=\"329\"><strong data-start=\"245\" data-end=\"329\">Zwei Stadtteile, ein Geschmackserlebnis: Erkunden Sie Hannover mit allen Sinnen!<\/strong><\/p>\n<p data-start=\"331\" data-end=\"713\">Begeben Sie sich auf eine genussvolle Reise durch die charmanten Stadtteile <strong data-start=\"407\" data-end=\"415\">List<\/strong> und <strong data-start=\"420\" data-end=\"432\">Oststadt<\/strong>, wo Gr\u00fcnderzeitarchitektur auf lebendige Gastronomieszene trifft. Zwischen gr\u00fcnen Alleen, individuellen Boutiquen und historischen Fassaden entdecken Sie kulinarische Perlen und spannende Stadtgeschichten \u2013 ideal f\u00fcr Feinschmecker, Hannover-Liebhaber und Neugierige gleicherma\u00dfen.<\/p>\n<p data-start=\"715\" data-end=\"1142\">Auf diesem gef\u00fchrten Rundgang erwarten Sie f\u00fcnf sorgf\u00e4ltig ausgew\u00e4hlte Stationen, die die kulinarische Vielfalt der Viertel widerspiegeln: von liebevoll gef\u00fchrten Delikatessenl\u00e4den \u00fcber trendige Caf\u00e9s bis hin zu traditionsreichen Restaurants. Probieren Sie regionale Spezialit\u00e4ten, internationale K\u00f6stlichkeiten und kleine \u00dcberraschungen, die Ihren Gaumen verw\u00f6hnen \u2013 jede Kostprobe ist inklusive und erz\u00e4hlt ihre eigene Geschichte.<\/p>\n<p data-start=\"1144\" data-end=\"1455\">Neben den kulinarischen Highlights erfahren Sie Spannendes zur Geschichte der beiden Stadtteile, zur Architektur und zu besonderen Orten, die oft im Verborgenen liegen. Unsere Guides kombinieren Insiderwissen mit Anekdoten und geben pers\u00f6nliche Tipps \u2013 f\u00fcr ein Erlebnis, das weit \u00fcber den Tellerrand hinausgeht.<\/p>\n<\/div>\n<\/div>\n","tt_galerie":["https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/G__8270-scaled-1.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/G__8130-scaled-1.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/G__8164-scaled-1.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/G__8179-1-scaled-1.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/Lister-Wedekindplatz-Martin-Kirchner-4.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2025\/06\/Lister-Meile-Hans-Zaglitsch-2.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2025\/06\/G__8196-scaled-1.jpg","https:\/\/www.hannover-tourismus.de\/wp-content\/uploads\/2026\/03\/IMG_1020.jpg"],"tt_p_veranstalter_name":"Hannover Marketing &amp; Tourismus GmbH","tt_p_veranstalter_nummer":"+49 511 12345 333","tt_p_veranstalter_mail":"staedtereise@visit-hannover.com","tt_o_tomas_id":"NDS00020140466005119","tt_o_preise":{"item-0":{"tt_o_preise_kat":"erwachsene","tt_o_preise":"46"}},"tt_o_preis_hinweise":"","tt_o_teilnehmerzahl":"","tt_o_sprache":["deutsch"],"tt_o_treffpunkt":"Hannover Lister Platz, 30163 Hannover, Deutschland","tt_p_tomas_id":"NDS00020140488941272","tt_p_preise":{"item-0":{"tt_p_preise_kat":"pro_person","tt_p_preise":"46"}},"tt_p_sprache":["deutsch","english"],"tt_p_fremdsprachenzuschlag":"true","tt_p_mindestteilnehmerzahl":"10","tt_p_maximalteilnehmerzahl":"18","tt_p_treffpunkt":"Hannover Lister Platz, 30163 Hannover, Deutschland","tt_p_seo_strasse":"Hannover Lister Platz","tt_p_seo_plz":"30163","tt_p_seo_ort":"Hannover","tt_o_seo_strasse":"Hannover Lister Platz","tt_o_seo_plz":"30163","tt_o_seo_ort":"Hannover"},"class_list":["post-5707","tickets-touren","type-tickets-touren","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hannover-tourismus.de\/da\/wp-json\/wp\/v2\/tickets-touren\/5707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hannover-tourismus.de\/da\/wp-json\/wp\/v2\/tickets-touren"}],"about":[{"href":"https:\/\/www.hannover-tourismus.de\/da\/wp-json\/wp\/v2\/types\/tickets-touren"}],"wp:attachment":[{"href":"https:\/\/www.hannover-tourismus.de\/da\/wp-json\/wp\/v2\/media?parent=5707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}